{"id":3760,"date":"2020-06-06T22:33:23","date_gmt":"2020-06-06T20:33:23","guid":{"rendered":"http:\/\/www.marinejugend-kiel.de\/?p=1164"},"modified":"2020-06-06T22:33:23","modified_gmt":"2020-06-06T20:33:23","slug":"zu-viel-wind-fuer-kleine-boote","status":"publish","type":"post","link":"https:\/\/www.marinejugend-kiel.de\/index.php\/2020\/06\/06\/zu-viel-wind-fuer-kleine-boote\/","title":{"rendered":"Zu viel Wind f\u00fcr kleine Boote"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__4134-1024x576.jpg\" alt=\"\" class=\"wp-image-1162\"\/><figcaption>Boot auf der Seite? Kein Problem \u2013 Konstantin und Louisa behalten ihre gute Laune. Foto: har<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Was f\u00fcr ein Segeltag! Regen, heftige B\u00f6en, zwischendrin wieder Sonnenschein und dazu ein paar Fischbr\u00f6tchen zur St\u00e4rkung &#8230; Zumindest hat das Wetter etwas anderes gehalten, als die diversen Wetter-Apps versprachen. Die sch\u00f6nen Pl\u00e4ne, die wir f\u00fcr heute gemacht hatten, waren nach einer Stunde Vorbereitung zu Beginn der Segelausbildung jedenfalls komplett hinf\u00e4llig. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__3929-1024x576.jpg\" alt=\"\" class=\"wp-image-1145\"\/><figcaption>Schon beim Auftakeln der Optis an Land gibt es viel mehr frische Luft aus einer Richtung, als den Teilnehmern lieb ist. Foto: har<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Beim Auftakeln der Optis f\u00fcr die erste Gruppe des Tages pfiff es schon ganz ordentlich an Land. Aber \u2013 haha \u2013 der Optimismus blieb, jedenfalls so lange, bis wir alle Jollen auf den Steg gestellt hatten. Eine B\u00f6e, und die Boote bewegten sich alle von allein in Richtung Wasser. Zum Gl\u00fcck griffen die Umstehenden zu, sodass die Jollen direkt an der Wasserkante zum Stoppen gebracht werden konnten. Was folgte, waren etwas unsichere \u00dcberlegungen und einige verzweifelte Blicke auf die Wetternachrichten auf den Smartphones sowie der Anzeigen des benachbarten Geomar-Instituts. Die Diskrepanz zwischen den elektronischen Anzeigen und der Realit\u00e4t war allerdings so offensichtlich, dass wir das Segeln mit den Optimisten abbrechen mussten, bevor es begonnen hatte.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__3936-1024x681.jpg\" alt=\"\" class=\"wp-image-1147\"\/><figcaption>Es sieht so harmlos und entspannt aus; doch wenige Augenblicke sp\u00e4ter versucht die gesamte Reihe Boote, sich ruckartig in Richtung Wasser zu verabschieden. Foto: har<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Schatzmeister Stephan hatte in der Not aber die rettende Idee, den sichtlich entt\u00e4uschten Optimist-Seglern eine Alternative anzubieten: Die Truppe machte sich nach dem Abriggen und Verstauen der kleinen Jollen gemeinsam mit Stephan, Tinka und Kai zum Liegeplatz des Kutters auf \u2013 \u201eRettungsboot-Segeln\u201c geht schlie\u00dflich (fast) immer. Auf das Gro\u00dfsegel verzichtete die \u201eFritjof\u201c-Besatzung dann aber lieber doch. Es hatte ja wohl seinen Grund, dass au\u00dfer unseren Booten mal wieder nicht viele andere Segler auf der F\u00f6rde zu sichten waren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aufr\u00e4umen in der \u201eJungen-Last\u201c<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">W\u00e4hrend die meisten anderen MJK-Mitglieder sich irgendwie um das praktische Segeln k\u00fcmmerten, bewegte derweil Sportwart Dennis im Hintergrund geradezu Berge: Das Malheur mit dem Rattenbesuch vor einigen Tagen hatte noch nicht die M\u00f6glichkeit einer weiteren Heimsuchung durch die findigen Vierbeiner ausgeschlossen. Also r\u00e4umte Dennis den Umkleideraum f\u00fcr die Jungen, die so genannte \u201eJungen-Last\u201c,  aus. Denn dort ist einiges Bootszubeh\u00f6r gestaut: Persennige, Segel und viele andere schwere Dinge. Die stapelten sich kurz darauf in der Bootshalle. Und nachdem Dennis dann auch noch mit dem Besen durch die Umkleide gefegt hatte, W\u00e4nde und Decke abgesucht hatte, brachte er alles ordentlich wieder an Ort und Stelle.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"http:\/\/www.marinejugend-kiel.de\/wp-content\/uploads\/2020\/06\/K3__4020-1024x576.jpg\" alt=\"\" class=\"wp-image-1155\"\/><figcaption>Wind, Regen \u2013 f\u00fcr einen Marinekutter sind das nicht echte Herausforderungen. Foto: har<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Auf dem Wasser waren in der zweiten Gruppe die gr\u00f6\u00dferen Jollen mit den Teilnehmern unterwegs, die es trotz der \u00e4u\u00dferen Bedingungen wissen wollten. Schriftwart Dieter warf einen pr\u00fcfenden Blick zum Himmel, drehte sich zu den anderen Betreuern um und fragte ganz trocken: \u201eWie lange gebt Ihr ihnen \u2013 bis zum ersten Kentern?\u201c Die Antwort war: nicht lange. Und so war es auch. Malte machte sich auf dem Laser mit einem kleineren Segel auf den Weg. Aber irgendwann erwischte ihn eine Regenb\u00f6e mit voller Wucht und legte sein Gef\u00e4hrt auf die Seite. Routiniert stieg er kurz darauf wieder ein. In dieser Stunde erwischte es ihn noch ein zweites Mal. Dann zog er vern\u00fcnftigerweise die Rei\u00dfleine und steuerte den Steg an.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__4069-1024x576.jpg\" alt=\"\" class=\"wp-image-1159\"\/><figcaption>Da ist beim besten Willen nichts mehr zu machen. Malte steigt aus \u2013 aber gleich wieder ein. Foto: har<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Sehr tapfer hielten sich auch Louisa und Konstantin in dem sonst sehr gutm\u00fctigen \u201eFloh\u201c. Aber selbst der gab irgendwann auf. Und so gutm\u00fctig diese Jolle beim Segeln ist, so zickig benimmt sie sich, wenn sie nach dem Durchkentern wieder aufgerichtet werden muss. Die beiden Besatzungsmitglieder verloren in keinem Moment den Humor. Lachend drehten sie mit dem gekenterten \u201eFloh\u201c Runden im Wasser, bis sich die Jolle tats\u00e4chlich endg\u00fcltig wieder aufrichtete. Nach dem Leersegeln ging es noch eine ganze Weile z\u00fcgig \u00fcber die F\u00f6rde, bis K\u00e4lte und N\u00e4sse auch dieses Boot wieder Richtung Heimatsteg f\u00fchrte.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__4106-1024x576.jpg\" alt=\"\" class=\"wp-image-1160\"\/><figcaption>Auch eine konventionelle Jolle verlangt ab und zu nach ein bisschen Akrobatik. Foto: har<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eZu Haus\u201c hatte auch der Kutter angelegt. Die Crew verlangte nach einer St\u00e4rkung. In Marine-Jugend-Kiel-Kreisen bedeutet das in der Saison Schlange stehen vor dem n\u00e4chsten Fischbr\u00f6tchen-Stand. Gl\u00fccklicherweise machte der Regen genau in dieser Zeit ebenfalls Pause. Die Seglerinnen und Segler hatten also die Gelegenheit zu essen \u2013 und ein bisschen  zu trocknen. Nach einer halben Stunde ging es wieder los, um \u201eFritjof\u201c sowie das gro\u00dfe Motorboot zu den Hafenliegepl\u00e4tzen zur\u00fcckzubringen. Nat\u00fcrlich fing es dann wieder kr\u00e4ftig zu regnen an. Ein richtig sch\u00f6ner Segeltag eben. <br><em>Klaas<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__4138-1024x576.jpg\" alt=\"\" class=\"wp-image-1163\"\/><figcaption>Muss sein: Aufklaren, Saubermachen, Trockenlegen \u2013 des Materials, nicht der Segler. Foto: har<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__4067-1024x576.jpg\" alt=\"\" data-id=\"1158\" data-full-url=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__4067.jpg\" data-link=\"http:\/\/www.marinejugend-kiel.de\/k3__4067\/\" class=\"wp-image-1158\"\/><figcaption class=\"blocks-gallery-item__caption\">Segeln mit richtig Geschwindigeit \u2013 und niemand im Weg. Foto: har<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__4055-1024x576.jpg\" alt=\"\" data-id=\"1157\" data-full-url=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__4055.jpg\" data-link=\"http:\/\/www.marinejugend-kiel.de\/k3__4055\/\" class=\"wp-image-1157\"\/><figcaption class=\"blocks-gallery-item__caption\">Bei diesem Wetter sind drei Segel genug &#8230; Foto: har<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"http:\/\/www.marinejugend-kiel.de\/wp-content\/uploads\/2020\/06\/K3__4047-1024x576.jpg\" alt=\"\" data-id=\"1156\" data-full-url=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__4047-scaled-1.jpg\" data-link=\"http:\/\/www.marinejugend-kiel.de\/k3__4047\/\" class=\"wp-image-1156\"\/><figcaption class=\"blocks-gallery-item__caption\">Ohne auf der Kante zu sitzen, geht heute gar nichts. Foto: har<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__3964-1024x576.jpg\" alt=\"\" data-id=\"1152\" data-full-url=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__3964.jpg\" data-link=\"http:\/\/www.marinejugend-kiel.de\/k3__3964\/\" class=\"wp-image-1152\"\/><figcaption class=\"blocks-gallery-item__caption\">J\u00f6rn und Nicola haben ein wachsames Auge auf die Seglerinnen und Segler. Foto: har<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__3995-1024x681.jpg\" alt=\"\" data-id=\"1154\" data-full-url=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__3995.jpg\" data-link=\"http:\/\/www.marinejugend-kiel.de\/k3__3995\/\" class=\"wp-image-1154\"\/><figcaption class=\"blocks-gallery-item__caption\">Steht der Flieger halbwegs? Kai schaut nach. Foto: har<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__3971-1024x576.jpg\" alt=\"\" data-id=\"1153\" data-full-url=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__3971.jpg\" data-link=\"http:\/\/www.marinejugend-kiel.de\/k3__3971\/\" class=\"wp-image-1153\"\/><figcaption class=\"blocks-gallery-item__caption\">Der \u201eFloh\u201c braucht richtig Wind, um sich auf die Seite zu legen. Aber dann &#8230; Foto: har<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__3947-1024x681.jpg\" alt=\"\" data-id=\"1150\" data-full-url=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__3947.jpg\" data-link=\"http:\/\/www.marinejugend-kiel.de\/k3__3947\/\" class=\"wp-image-1150\"\/><figcaption class=\"blocks-gallery-item__caption\">Es gibt kein schlechtes Wetter. Foto: har<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__3961-1024x681.jpg\" alt=\"\" data-id=\"1151\" data-full-url=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__3961.jpg\" data-link=\"http:\/\/www.marinejugend-kiel.de\/k3__3961\/\" class=\"wp-image-1151\"\/><figcaption class=\"blocks-gallery-item__caption\">Hier sieht es nur gem\u00fctlich aus, ist es aber nicht. Foto: har<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__3945-1024x681.jpg\" alt=\"\" data-id=\"1149\" data-full-url=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__3945.jpg\" data-link=\"http:\/\/www.marinejugend-kiel.de\/k3__3945\/\" class=\"wp-image-1149\"\/><figcaption class=\"blocks-gallery-item__caption\">Auch mit dem kleineren Segel musste man auf dem \u201eLaser\u201c heute richtig arbeiten. Foto: har<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__3931-1024x576.jpg\" alt=\"\" data-id=\"1146\" data-full-url=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__3931.jpg\" data-link=\"http:\/\/www.marinejugend-kiel.de\/k3__3931\/\" class=\"wp-image-1146\"\/><figcaption class=\"blocks-gallery-item__caption\">Auftakeln, abtakeln \u2013 die Arbeit an und mit den Optis war nicht sehr lustig heute. Foto: har<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" src=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__4121-1024x576.jpg\" alt=\"\" data-id=\"1161\" data-full-url=\"https:\/\/wp.mj-kiel.de\/wp-content\/uploads\/2020\/06\/K3__4121.jpg\" data-link=\"http:\/\/www.marinejugend-kiel.de\/k3__4121\/\" class=\"wp-image-1161\"\/><figcaption class=\"blocks-gallery-item__caption\">Gutes Zureden half nicht, um die Jolle aufzurichten, nur schiere Muskelkraft. Foto: har<\/figcaption><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Was f\u00fcr ein Segeltag! Regen, heftige B\u00f6en, zwischendrin wieder Sonnenschein und dazu ein paar Fischbr\u00f6tchen zur St\u00e4rkung &#8230; Zumindest hat das Wetter etwas anderes gehalten, als die diversen Wetter-Apps versprachen. Die sch\u00f6nen Pl\u00e4ne, die wir f\u00fcr heute gemacht hatten, waren nach einer Stunde Vorbereitung zu Beginn der Segelausbildung jedenfalls komplett hinf\u00e4llig. Beim Auftakeln der Optis &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.marinejugend-kiel.de\/index.php\/2020\/06\/06\/zu-viel-wind-fuer-kleine-boote\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eZu viel Wind f\u00fcr kleine Boote\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":2141,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-3760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.marinejugend-kiel.de\/index.php\/wp-json\/wp\/v2\/posts\/3760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marinejugend-kiel.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.marinejugend-kiel.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.marinejugend-kiel.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marinejugend-kiel.de\/index.php\/wp-json\/wp\/v2\/comments?post=3760"}],"version-history":[{"count":0,"href":"https:\/\/www.marinejugend-kiel.de\/index.php\/wp-json\/wp\/v2\/posts\/3760\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.marinejugend-kiel.de\/index.php\/wp-json\/wp\/v2\/media\/2141"}],"wp:attachment":[{"href":"https:\/\/www.marinejugend-kiel.de\/index.php\/wp-json\/wp\/v2\/media?parent=3760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.marinejugend-kiel.de\/index.php\/wp-json\/wp\/v2\/categories?post=3760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.marinejugend-kiel.de\/index.php\/wp-json\/wp\/v2\/tags?post=3760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}